{"id":347,"name":"Laura Restrepo","url":"https:\/\/mascolombia.com\/en\/","description":"Gestora de Contenidos Web. Organiza y presenta respuestas a preguntas comunes sobre alimentos y cuidados del hogar, siempre con datos curiosos y \u00fatiles.","link":"https:\/\/mascolombia.com\/en\/columnist\/laura-restrepo\/","slug":"laura-restrepo","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f1d337ca80a035c1a52204dec5451e7241e9f09e8937b37587ab3f1eae7db065?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f1d337ca80a035c1a52204dec5451e7241e9f09e8937b37587ab3f1eae7db065?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f1d337ca80a035c1a52204dec5451e7241e9f09e8937b37587ab3f1eae7db065?s=96&d=mm&r=g"},"meta":[],"acf":[],"amp_review_panel_dismissed_for_template_mode":"","amp_dev_tools_enabled":false,"_links":{"self":[{"href":"https:\/\/mascolombia.com\/en\/wp-json\/wp\/v2\/users\/347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascolombia.com\/en\/wp-json\/wp\/v2\/users"}]}}